{"id":11351,"date":"2023-03-16T17:13:17","date_gmt":"2023-03-16T17:13:17","guid":{"rendered":"https:\/\/onlinebettingnewyork.com\/index.php\/2023\/03\/16\/jalen-carter-pleads-no-contest-to-reckless-driving-racing\/"},"modified":"2023-03-16T17:13:17","modified_gmt":"2023-03-16T17:13:17","slug":"jalen-carter-pleads-no-contest-to-reckless-driving-racing","status":"publish","type":"post","link":"https:\/\/onlinebettingnewyork.com\/index.php\/2023\/03\/16\/jalen-carter-pleads-no-contest-to-reckless-driving-racing\/","title":{"rendered":"Jalen Carter pleads no contest to reckless driving, racing"},"content":{"rendered":"<p>Jalen Carter was sentenced to 12 months of probation, a fine and community service following his plea Thursday.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jalen Carter was sentenced to 12 months of probation, a fine and community service following his plea Thursday.<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/posts\/11351"}],"collection":[{"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/comments?post=11351"}],"version-history":[{"count":0,"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/posts\/11351\/revisions"}],"wp:attachment":[{"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/media?parent=11351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/categories?post=11351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinebettingnewyork.com\/index.php\/wp-json\/wp\/v2\/tags?post=11351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}